{"id":432,"count":3,"description":"","link":"https:\/\/www.puresakeisgood.com\/en\/product-category\/sake\/toutes-options\/methode\/kimoto\/","name":"Kimoto","slug":"kimoto","taxonomy":"product_cat","parent":430,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Archives des Kimoto - Pure Sake is Good<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.puresakeisgood.com\/en\/product-category\/sake\/toutes-options\/methode\/kimoto\/\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Archives des Kimoto - Pure Sake is Good\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.puresakeisgood.com\/en\/product-category\/sake\/toutes-options\/methode\/kimoto\/\" \/>\n<meta property=\"og:site_name\" content=\"Pure Sake is Good\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.puresakeisgood.com\/wp-content\/uploads\/2021\/06\/41465015_10155930926257972_2128172448540000256_n.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/methode\/kimoto\/\",\"url\":\"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/methode\/kimoto\/\",\"name\":\"Archives des Kimoto - Pure Sake is Good\",\"isPartOf\":{\"@id\":\"https:\/\/www.puresakeisgood.com\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/methode\/kimoto\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/methode\/kimoto\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/www.puresakeisgood.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Les Sak\u00e9s\",\"item\":\"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Toutes autres options ..\",\"item\":\"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Par M\u00e9thode\",\"item\":\"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/methode\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Kimoto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.puresakeisgood.com\/#website\",\"url\":\"https:\/\/www.puresakeisgood.com\/\",\"name\":\"Pure Sake is Good\",\"description\":\"un sake junmai chaud c est encore mieux\",\"publisher\":{\"@id\":\"https:\/\/www.puresakeisgood.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.puresakeisgood.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.puresakeisgood.com\/#organization\",\"name\":\"Pure Sake is Good\",\"url\":\"https:\/\/www.puresakeisgood.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\/\/www.puresakeisgood.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.puresakeisgood.com\/wp-content\/uploads\/2020\/09\/cropped-cropped-logo-1.png\",\"contentUrl\":\"https:\/\/www.puresakeisgood.com\/wp-content\/uploads\/2020\/09\/cropped-cropped-logo-1.png\",\"width\":250,\"height\":250,\"caption\":\"Pure Sake is Good\"},\"image\":{\"@id\":\"https:\/\/www.puresakeisgood.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/PureSakeisGood\",\"https:\/\/www.instagram.com\/puresakeisgood\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Archives des Kimoto - Pure Sake is Good","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.puresakeisgood.com\/en\/product-category\/sake\/toutes-options\/methode\/kimoto\/","og_locale":"en_GB","og_type":"article","og_title":"Archives des Kimoto - Pure Sake is Good","og_url":"https:\/\/www.puresakeisgood.com\/en\/product-category\/sake\/toutes-options\/methode\/kimoto\/","og_site_name":"Pure Sake is Good","og_image":[{"width":960,"height":960,"url":"https:\/\/www.puresakeisgood.com\/wp-content\/uploads\/2021\/06\/41465015_10155930926257972_2128172448540000256_n.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/methode\/kimoto\/","url":"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/methode\/kimoto\/","name":"Archives des Kimoto - Pure Sake is Good","isPartOf":{"@id":"https:\/\/www.puresakeisgood.com\/#website"},"breadcrumb":{"@id":"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/methode\/kimoto\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/methode\/kimoto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/www.puresakeisgood.com\/"},{"@type":"ListItem","position":2,"name":"Les Sak\u00e9s","item":"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/"},{"@type":"ListItem","position":3,"name":"Toutes autres options ..","item":"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/"},{"@type":"ListItem","position":4,"name":"Par M\u00e9thode","item":"https:\/\/www.puresakeisgood.com\/categorie-produit\/sake\/toutes-options\/methode\/"},{"@type":"ListItem","position":5,"name":"Kimoto"}]},{"@type":"WebSite","@id":"https:\/\/www.puresakeisgood.com\/#website","url":"https:\/\/www.puresakeisgood.com\/","name":"Pure Sake is Good","description":"un sake junmai chaud c est encore mieux","publisher":{"@id":"https:\/\/www.puresakeisgood.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.puresakeisgood.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/www.puresakeisgood.com\/#organization","name":"Pure Sake is Good","url":"https:\/\/www.puresakeisgood.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/www.puresakeisgood.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.puresakeisgood.com\/wp-content\/uploads\/2020\/09\/cropped-cropped-logo-1.png","contentUrl":"https:\/\/www.puresakeisgood.com\/wp-content\/uploads\/2020\/09\/cropped-cropped-logo-1.png","width":250,"height":250,"caption":"Pure Sake is Good"},"image":{"@id":"https:\/\/www.puresakeisgood.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/PureSakeisGood","https:\/\/www.instagram.com\/puresakeisgood\/"]}]}},"_links":{"self":[{"href":"https:\/\/www.puresakeisgood.com\/en\/wp-json\/wp\/v2\/product_cat\/432"}],"collection":[{"href":"https:\/\/www.puresakeisgood.com\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/www.puresakeisgood.com\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/www.puresakeisgood.com\/en\/wp-json\/wp\/v2\/product_cat\/430"}],"wp:post_type":[{"href":"https:\/\/www.puresakeisgood.com\/en\/wp-json\/wp\/v2\/product?product_cat=432"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}